{"id":1033605,"date":"2025-03-07T09:46:59","date_gmt":"2025-03-07T13:46:59","guid":{"rendered":"https:\/\/edenorte.com.do\/transparencia\/?page_id=1033605"},"modified":"2025-05-01T08:01:31","modified_gmt":"2025-05-01T12:01:31","slug":"administracion-del-programa-convenio-de-prestamo-y-pgas","status":"publish","type":"page","link":"https:\/\/edenorte.com.do\/transparencia\/administracion-del-programa-convenio-de-prestamo-y-pgas\/","title":{"rendered":"Administraci\u00f3n del Programa"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1033605\" class=\"elementor elementor-1033605\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e540eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e540eb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cfd05d5\" data-id=\"cfd05d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9af81e1 elementor-widget elementor-widget-wpdmcategory\" data-id=\"9af81e1\" data-element_type=\"widget\" data-widget_type=\"wpdmcategory.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class='w3eden'>\n    <div class=''>\n\n        \n        <div id=\"content_wpdm_package_1\">\n            <div class='row'><div class='col-lg-12 col-md-12 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\" src=\"https:\/\/edenorte.com.do\/transparencia\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/edenorte.com.do\/transparencia\/download\/convenio-de-prestamo\/'>Convenio de Pr\u00e9stamo<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 12.23 MB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/edenorte.com.do\/transparencia\/download\/convenio-de-prestamo\/?wpdmdl=1034423&refresh=6a579e7a60ef91784127098\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-12 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\" src=\"https:\/\/edenorte.com.do\/transparencia\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/edenorte.com.do\/transparencia\/download\/plan-de-compromiso-ambiental-y-social-pcas-julio-2024\/'>Environmental and Social Commitment Plan (ESCP) - Nov. 26-2025<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 377 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/edenorte.com.do\/transparencia\/download\/plan-de-compromiso-ambiental-y-social-pcas-julio-2024\/?wpdmdl=1034388&refresh=6a579e7a635d21784127098\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><\/div>                    <\/div>\n\n        <div style='clear:both'><\/div>\n    <\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-131e0490 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"131e0490\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-154e6745\" data-id=\"154e6745\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78b0589e elementor-widget elementor-widget-shortcode\" data-id=\"78b0589e\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_small\"><div class=\"vc_col-sm-12 wpb_column\"><div class=\"vc_column-inner\"><div class=\"w-message with_icon type_info\"><div class=\"w-message-icon\"><i class=\"fa fa-check-square-o\"><\/i><\/div><div class=\"w-message-body\"><p>Si no puede visualizar nuestros documentos, es posible que necesite alguno de los siguientes programas:\r\n<ul>\r\n \t<li>Para Documentos en Pdf:\r\n<ol>\r\n \t<li><a href=\"https:\/\/get.adobe.com\/es\/reader\/\" target=\"_blank\" rel=\"noopener\">Adobe Reader <\/a><\/li>\r\n<\/ol>\r\n<\/li>\r\n \t<li>Para Documentos en Doc, Excel, Ods, Csv, entre otros tipos:\r\n<ol>\r\n \t<li><a href=\"https:\/\/support.microsoft.com\/es-es\/office\/obtenga-acceso-r%c3%a1pido-a-sus-archivos-de-office-en-el-explorador-dc1024b4-92be-46eb-81a7-aea85368baa0?ui=es-es&amp;rs=es-es&amp;ad=es\" target=\"_blank\" rel=\"noopener\">Microsoft Office:<\/a> <a href=\"https:\/\/chrome.google.com\/webstore\/detail\/office\/ndjpnladcallmjemlbaebfadecfhkepb?hl=es-419\" target=\"_blank\" rel=\"noopener\">Extensi\u00f3n para Chrome<\/a> -\u00a0<a href=\"https:\/\/www.microsoft.com\/es-us\/p\/office-online\/9nblggh4v88g?activetab=pivot%3aoverviewtab\" target=\"_blank\" rel=\"noopener\">Extensi\u00f3n para\u00a0 Microsoft Edge.<\/a><\/li>\r\n \t<li><a href=\"https:\/\/www.google.com\/intl\/es\/docs\/about\/\" target=\"_blank\" rel=\"noopener\">Google Documentos<\/a>.<\/li>\r\n<\/ol>\r\n<\/li>\r\n<\/ul>\r\n<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/section><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<div style=\"clear:both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Plan de Compromiso Ambiental y Social (PCAS) &#8211; julio 2024 1 archivo(s) 768.48 KB Descargar<\/p>\n","protected":false},"author":15,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1033605","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/edenorte.com.do\/transparencia\/wp-json\/wp\/v2\/pages\/1033605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edenorte.com.do\/transparencia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/edenorte.com.do\/transparencia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/edenorte.com.do\/transparencia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/edenorte.com.do\/transparencia\/wp-json\/wp\/v2\/comments?post=1033605"}],"version-history":[{"count":21,"href":"https:\/\/edenorte.com.do\/transparencia\/wp-json\/wp\/v2\/pages\/1033605\/revisions"}],"predecessor-version":[{"id":1034418,"href":"https:\/\/edenorte.com.do\/transparencia\/wp-json\/wp\/v2\/pages\/1033605\/revisions\/1034418"}],"wp:attachment":[{"href":"https:\/\/edenorte.com.do\/transparencia\/wp-json\/wp\/v2\/media?parent=1033605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}